{"id":3707,"date":"2022-05-08T14:40:44","date_gmt":"2022-05-08T07:40:44","guid":{"rendered":"https:\/\/library.wu.ac.th\/km\/?p=3707"},"modified":"2022-09-27T14:23:12","modified_gmt":"2022-09-27T07:23:12","slug":"%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%99%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%87","status":"publish","type":"post","link":"https:\/\/library.wu.ac.th\/km\/%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%99%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%aa%e0%b8%b3%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%87\/","title":{"rendered":"\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25"},"content":{"rendered":"\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">          \u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49 \u0e43\u0e19\u0e43\u0e08\u0e25\u0e36\u0e01\u0e46 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32 &#8220;\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25&#8221; \u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e22\u0e32\u0e01\u0e2b\u0e23\u0e2d\u0e01<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e15\u0e31\u0e27\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">\u0e41\u0e25\u0e49\u0e27\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e07\u0e44\u0e27\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e30\u0e41\u0e19\u0e19\u0e1c\u0e25\u0e2a\u0e2d\u0e1a\u0e21\u0e31\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e19\u0e17\u0e32\u0e07\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30 \u0e40\u0e01\u0e23\u0e14\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e41\u0e04\u0e48\u0e19\u0e35\u0e49 73%<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">          <\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-large-font-size wp-block-paragraph\">\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49\u0e40\u0e02\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e40\u0e23\u0e32\u0e15\u0e32\u0e21\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">         \u0e1a\u0e17\u0e41\u0e23\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e32\u0e21\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e17\u0e17\u0e35\u0e48 2 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1a\u0e17\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e17\u0e17\u0e35\u0e48 4 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1a\u0e17\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e1a\u0e17\u0e17\u0e35\u0e48 5 \u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e02\u0e35\u0e22\u0e27\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">          \u0e2d\u0e48\u0e32\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e41\u0e2d\u0e1a\u0e01\u0e31\u0e07\u0e27\u0e25\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e14\u0e41\u0e19\u0e48\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e21\u0e32\u0e01 \u0e46 \u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e2a\u0e23\u0e38\u0e1b\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2d\u0e48\u0e32\u0e19 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e02\u0e2d\u0e1a\u0e2d\u0e01\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e27\u0e04\u0e37\u0e2d &#8220;\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25&#8221; \u0e21\u0e32\u0e40\u0e25\u0e48\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e31\u0e19\u0e1f\u0e31\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e48\u0e30<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22274-1-1024x768.jpg\" alt=\"\" class=\"wp-image-3712\" srcset=\"https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22274-1-1024x768.jpg 1024w, https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22274-1-300x225.jpg 300w, https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22274-1-768x576.jpg 768w, https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22274-1.jpg 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-large-font-size wp-block-paragraph\">\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25<\/p>\n\n\n\n<p class=\"has-text-align-left has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">         \u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e41\u0e2d\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e40\u0e19\u0e49\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"723\" height=\"243\" src=\"https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22273.jpg\" alt=\"\" class=\"wp-image-3713\" srcset=\"https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22273.jpg 723w, https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22273-300x101.jpg 300w\" sizes=\"(max-width: 723px) 100vw, 723px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-vivid-red-color has-text-color has-large-font-size wp-block-paragraph\">\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">          1) <strong>\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25<\/strong> \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e2d\u0e21\u0e23\u0e27\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e21\u0e04\u0e37\u0e19\u0e08\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e21\u0e04\u0e37\u0e19\u0e1a\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e17\u0e33\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e41\u0e2d\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e08\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">          \u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14 \u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e47\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 &nbsp;&nbsp;\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33 Road Map \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e44\u0e27\u0e49 \u0e2d\u0e31\u0e19\u0e08\u0e30\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><img decoding=\"async\" width=\"900\" height=\"623\" src=\"https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22272.jpg\" alt=\"\" class=\"wp-image-3716\" srcset=\"https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22272.jpg 900w, https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22272-300x208.jpg 300w, https:\/\/library.wu.ac.th\/km\/wp-content\/uploads\/sites\/9\/2022\/05\/22272-768x532.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">2) <strong>\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e19\u0e27\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e32\u0e07<\/strong>\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21 \u0e08\u0e31\u0e14\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">3) <strong>\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e08\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e08\u0e32\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">4) <strong>\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e31\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u0e41\u0e25\u0e49\u0e27\u0e04\u0e38\u0e13\u0e25\u0e48\u0e30 \u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e31\u0e1a\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e38\u0e04\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e1a\u0e49\u0e32\u0e07  \u0e04\u0e38\u0e13\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e2b\u0e47\u0e19 \u201c\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u201d \u0e14\u0e49\u0e32\u0e19\u0e43\u0e14\u0e1a\u0e49\u0e32\u0e07 \u0e21\u0e32\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e04\u0e48\u0e30<\/p><\/blockquote>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color wp-block-paragraph\">\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25: \u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \/ WU &#8211; WU013<\/p>\n<p>Views: 163<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e33\u0e44\u0e21\u0e16\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49 \u0e43\u0e19\u0e43\u0e08\u0e25\u0e36\u0e01\u0e46 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32 &#8220;\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25&#8221; \u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e22\u0e32\u0e01\u0e2b\u0e23\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e15\u0e31\u0e27\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e07\u0e44\u0e27\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e30\u0e41\u0e19\u0e19\u0e1c\u0e25\u0e2a\u0e2d\u0e1a\u0e21\u0e31\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e2a\u0e27\u0e19\u0e17\u0e32\u0e07\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30 \u0e40\u0e01\u0e23\u0e14\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e44\u0e14\u0e49\u0e21\u0e32\u0e41\u0e04\u0e48\u0e19\u0e35\u0e49 73% \u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e35\u0e49\u0e40\u0e02\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e40\u0e23\u0e32\u0e15\u0e32\u0e21\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30 \u0e1a\u0e17\u0e41\u0e23\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e32\u0e21\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e17\u0e17\u0e35\u0e48 2 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1a\u0e17\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e17\u0e17\u0e35\u0e48 4 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1a\u0e17\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u0e1a\u0e17\u0e17\u0e35\u0e48 5 \u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e02\u0e35\u0e22\u0e27\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2d\u0e48\u0e32\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e21\u0e35\u0e41\u0e2d\u0e1a\u0e01\u0e31\u0e07\u0e27\u0e25\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e14\u0e41\u0e19\u0e48\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e21\u0e32\u0e01 \u0e46&hellip;<\/p>\n","protected":false},"author":35,"featured_media":3710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[106,67],"tags":[119],"class_list":["post-3707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-106","category-67","tag-119"],"_links":{"self":[{"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/posts\/3707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/comments?post=3707"}],"version-history":[{"count":17,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/posts\/3707\/revisions"}],"predecessor-version":[{"id":5792,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/posts\/3707\/revisions\/5792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/media\/3710"}],"wp:attachment":[{"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/media?parent=3707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/categories?post=3707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/library.wu.ac.th\/km\/wp-json\/wp\/v2\/tags?post=3707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}